{"id":12102,"date":"2026-07-15T14:14:41","date_gmt":"2026-07-15T12:14:41","guid":{"rendered":"https:\/\/gijonbasket.com\/?p=12102"},"modified":"2026-07-15T14:16:03","modified_gmt":"2026-07-15T12:16:03","slug":"raul-lobaco-adios-al-alimerka-oviedo-baloncesto","status":"publish","type":"post","link":"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/","title":{"rendered":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos"},"content":{"rendered":"<p>El Alimerka Oviedo Baloncesto anunci\u00f3 la rescisi\u00f3n de contrato, con pago de su cl\u00e1usula, por parte de Ra\u00fal Lobaco que deja de pertenecer al conjunto ovetense.<\/p>\n\n\n\n<p>Cr\u00f3nica de una salida anunciada y cuyo futuro ser\u00e1 el Recoletas Salud San Pablo Burgos.<\/p>\n\n\n\n<p>Ra\u00fal Lobaco gracias a su rendimiento con el Alimerka Oviedo Baloncesto, dar\u00e1 el salto a la Liga Endesa, donde lleg\u00f3 a debutar disputando un encuentro con el Tecnyconta Zaragoza en la temporada 2017\/2018.<\/p>\n\n\n\n<p>Escolta de 25 a\u00f1os y 1.90 m., que milit\u00f3 las tres \u00faltimas temporadas en el Alimerka Oviedo Baloncesto, en su segunda etapa en el conjunto ovetense.<\/p>\n\n\n\n<p>Ra\u00fal Lobaco cierra su segunda etapa en el Alimerka Oviedo Baloncesto (2023\/2024; 2024\/2025; 2025\/2026) tras la primera en la temporada 2021\/2022.<\/p>\n\n\n\n<p>Esta pasada temporada Ra\u00fal Lobaco promedi\u00f3 12 ppp; 4.2 rpp (Temporada Regular) y 9.6 ppp; 4.8 rpp (Play-Offs Ascenso a Liga Endesa).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\" alt=\"\" class=\"wp-image-12105\" srcset=\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png 819w, https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-240x300.png 240w, https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-768x960.png 768w, https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-10x12.png 10w, https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El Alimerka Oviedo Baloncesto anunci\u00f3 la rescisi\u00f3n de contrato, con pago de su cl\u00e1usula, por parte de Ra\u00fal Lobaco que deja de pertenecer al conjunto ovetense. Cr\u00f3nica de una salida anunciada y cuyo futuro ser\u00e1 el Recoletas Salud San Pablo Burgos. Ra\u00fal Lobaco gracias a su rendimiento con el Alimerka Oviedo Baloncesto, dar\u00e1 el salto&hellip;&nbsp;<a href=\"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-12102","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket\" \/>\n<meta property=\"og:description\" content=\"El Alimerka Oviedo Baloncesto anunci\u00f3 la rescisi\u00f3n de contrato, con pago de su cl\u00e1usula, por parte de Ra\u00fal Lobaco que deja de pertenecer al conjunto ovetense. Cr\u00f3nica de una salida anunciada y cuyo futuro ser\u00e1 el Recoletas Salud San Pablo Burgos. Ra\u00fal Lobaco gracias a su rendimiento con el Alimerka Oviedo Baloncesto, dar\u00e1 el salto&hellip;&nbsp;Read More &raquo;Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\" \/>\n<meta property=\"og:site_name\" content=\"gijonbasket\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T12:14:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T12:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\" \/>\n<meta name=\"author\" content=\"Cesar Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cesar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\"},\"author\":{\"name\":\"Cesar Morales\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0\"},\"headline\":\"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos\",\"datePublished\":\"2026-07-15T12:14:41+00:00\",\"dateModified\":\"2026-07-15T12:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\"},\"wordCount\":156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gijonbasket.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\",\"articleSection\":[\"noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\",\"url\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\",\"name\":\"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket\",\"isPartOf\":{\"@id\":\"https:\/\/gijonbasket.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\",\"datePublished\":\"2026-07-15T12:14:41+00:00\",\"dateModified\":\"2026-07-15T12:16:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage\",\"url\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\",\"contentUrl\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gijonbasket.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gijonbasket.com\/#website\",\"url\":\"https:\/\/gijonbasket.com\/\",\"name\":\"gijonbasket\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gijonbasket.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gijonbasket.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gijonbasket.com\/#organization\",\"name\":\"gijonbasket\",\"url\":\"https:\/\/gijonbasket.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg\",\"contentUrl\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg\",\"width\":2000,\"height\":550,\"caption\":\"gijonbasket\"},\"image\":{\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0\",\"name\":\"Cesar Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g\",\"caption\":\"Cesar Morales\"},\"url\":\"https:\/\/gijonbasket.com\/en\/author\/cesar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/","og_locale":"en_US","og_type":"article","og_title":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket","og_description":"El Alimerka Oviedo Baloncesto anunci\u00f3 la rescisi\u00f3n de contrato, con pago de su cl\u00e1usula, por parte de Ra\u00fal Lobaco que deja de pertenecer al conjunto ovetense. Cr\u00f3nica de una salida anunciada y cuyo futuro ser\u00e1 el Recoletas Salud San Pablo Burgos. Ra\u00fal Lobaco gracias a su rendimiento con el Alimerka Oviedo Baloncesto, dar\u00e1 el salto&hellip;&nbsp;Read More &raquo;Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos","og_url":"https:\/\/gijonbasket.com\/en\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/","og_site_name":"gijonbasket","article_published_time":"2026-07-15T12:14:41+00:00","article_modified_time":"2026-07-15T12:16:03+00:00","og_image":[{"url":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png"}],"author":"Cesar Morales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cesar Morales","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#article","isPartOf":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/"},"author":{"name":"Cesar Morales","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0"},"headline":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos","datePublished":"2026-07-15T12:14:41+00:00","dateModified":"2026-07-15T12:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/"},"wordCount":156,"commentCount":0,"publisher":{"@id":"https:\/\/gijonbasket.com\/#organization"},"image":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage"},"thumbnailUrl":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png","articleSection":["noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/","url":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/","name":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos - gijonbasket","isPartOf":{"@id":"https:\/\/gijonbasket.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage"},"image":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage"},"thumbnailUrl":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png","datePublished":"2026-07-15T12:14:41+00:00","dateModified":"2026-07-15T12:16:03+00:00","breadcrumb":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#primaryimage","url":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png","contentUrl":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2026\/07\/image-18-819x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/gijonbasket.com\/2026\/07\/15\/raul-lobaco-adios-al-alimerka-oviedo-baloncesto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gijonbasket.com\/"},{"@type":"ListItem","position":2,"name":"Ra\u00fal Lobaco adi\u00f3s al Alimerka Oviedo Baloncesto rumbo al Recoletas Salud San Pablo Burgos"}]},{"@type":"WebSite","@id":"https:\/\/gijonbasket.com\/#website","url":"https:\/\/gijonbasket.com\/","name":"gijonbasket","description":"","publisher":{"@id":"https:\/\/gijonbasket.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gijonbasket.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gijonbasket.com\/#organization","name":"gijonbasket","url":"https:\/\/gijonbasket.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/","url":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg","contentUrl":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg","width":2000,"height":550,"caption":"gijonbasket"},"image":{"@id":"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0","name":"Cesar Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g","caption":"Cesar Morales"},"url":"https:\/\/gijonbasket.com\/en\/author\/cesar\/"}]}},"_links":{"self":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/comments?post=12102"}],"version-history":[{"count":3,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12102\/revisions"}],"predecessor-version":[{"id":12107,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12102\/revisions\/12107"}],"wp:attachment":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/media?parent=12102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/categories?post=12102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/tags?post=12102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}