{"id":12376,"date":"2026-07-28T07:40:44","date_gmt":"2026-07-28T05:40:44","guid":{"rendered":"https:\/\/gijonbasket.com\/?p=12376"},"modified":"2026-07-28T07:42:34","modified_gmt":"2026-07-28T05:42:34","slug":"joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria","status":"publish","type":"post","link":"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/","title":{"rendered":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria"},"content":{"rendered":"<p>El Dreamland Gran Canaria anunci\u00f3 el fichaje de Joe Cremo para la pr\u00f3xima temporada.<\/p>\n\n\n\n<p>Escolta estadounidense de 29 a\u00f1os y 1.93 m, procedente del Leyma Coru\u00f1a con el que la pasada temporada conquist\u00f3 la Final Four de Ascenso a Liga Endesa, logrando el retorno del conjunto coru\u00f1\u00e9s a la m\u00e1xima categor\u00eda del baloncesto nacional.<\/p>\n\n\n\n<p>Joe Cremo acumula cinco temporadas en Espa\u00f1a desde su llegada en la temporada 2021\/2022 a las filas del Teknei Bizkaia Zornotza (LEB Plata).<\/p>\n\n\n\n<p>Salto al UBU Tizona en la temporada 2022\/2023, hist\u00f3rica para el conjunto burgal\u00e9s, conquistando el doblete como campe\u00f3n LEB Plata y Copa LEB Plata para lograr el ascenso a LEB Oro.<\/p>\n\n\n\n<p>Joe Cremo se manutvo una temporada m\u00e1s con el Grupo Ureta Tizona Burgos (2023\/2024) en LEB Oro.<\/p>\n\n\n\n<p>Sus dos \u00faltimas temporadas en la categor\u00eda ya con la denominaci\u00f3n de Primera FEB son de absoluto \u00e9xito para Jor Cremo.<\/p>\n\n\n\n<p>Doblete con el Silb\u00f6 San Pablo Burgos en la temporada 2024\/2025, conquistando el t\u00edtulo de Primera FEB m\u00e1s la Copa Espa\u00f1a y lograr el ascenso a Liga Endesa.<\/p>\n\n\n\n<p>La pasada temporada en el Leyma Coru\u00f1a, conquist\u00f3 la Final Four de Ascenso a Liga Endesa y logrando as\u00ed su segundo ascenso consecutivo a la segunda categor\u00eda del baloncesto nacional.<\/p>\n\n\n\n<p>Joe Cremo cuenta con tres ascensos de categor\u00eda, uno de LEB Plata a LEB Oro, m\u00e1s otros dos a Liga Endesa en tan s\u00f3lo cinco temporadas.<\/p>\n\n\n\n<p>La pasada temporada con el Leyma Coru\u00f1a, Joe Cremo promedi\u00f3 11.4 ppp; 2.7 rpp (Temporada Regular) y 11.9 ppp; 2.5 rpp (Play-Offs Fase de Ascenso a Liga Endesa).<\/p>\n\n\n\n<p>El nuevo reto para Joe Cremo con el Dreamland Gran Canaria ser\u00e1 lograr el tercer ascenso consecutivo a Liga Endesa.<\/p>","protected":false},"excerpt":{"rendered":"<p>El Dreamland Gran Canaria anunci\u00f3 el fichaje de Joe Cremo para la pr\u00f3xima temporada. Escolta estadounidense de 29 a\u00f1os y 1.93 m, procedente del Leyma Coru\u00f1a con el que la pasada temporada conquist\u00f3 la Final Four de Ascenso a Liga Endesa, logrando el retorno del conjunto coru\u00f1\u00e9s a la m\u00e1xima categor\u00eda del baloncesto nacional. Joe&hellip;&nbsp;<a href=\"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Joe Cremo nuevo fichaje del Dreamland Gran Canaria<\/span><\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-12376","post","type-post","status-publish","format-standard","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket\" \/>\n<meta property=\"og:description\" content=\"El Dreamland Gran Canaria anunci\u00f3 el fichaje de Joe Cremo para la pr\u00f3xima temporada. Escolta estadounidense de 29 a\u00f1os y 1.93 m, procedente del Leyma Coru\u00f1a con el que la pasada temporada conquist\u00f3 la Final Four de Ascenso a Liga Endesa, logrando el retorno del conjunto coru\u00f1\u00e9s a la m\u00e1xima categor\u00eda del baloncesto nacional. Joe&hellip;&nbsp;Read More &raquo;Joe Cremo nuevo fichaje del Dreamland Gran Canaria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\" \/>\n<meta property=\"og:site_name\" content=\"gijonbasket\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-28T05:40:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T05:42:34+00:00\" \/>\n<meta name=\"author\" content=\"Cesar Morales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cesar Morales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\"},\"author\":{\"name\":\"Cesar Morales\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0\"},\"headline\":\"Joe Cremo nuevo fichaje del Dreamland Gran Canaria\",\"datePublished\":\"2026-07-28T05:40:44+00:00\",\"dateModified\":\"2026-07-28T05:42:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\"},\"wordCount\":298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gijonbasket.com\/#organization\"},\"articleSection\":[\"noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\",\"url\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\",\"name\":\"Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket\",\"isPartOf\":{\"@id\":\"https:\/\/gijonbasket.com\/#website\"},\"datePublished\":\"2026-07-28T05:40:44+00:00\",\"dateModified\":\"2026-07-28T05:42:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/gijonbasket.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joe Cremo nuevo fichaje del Dreamland Gran Canaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gijonbasket.com\/#website\",\"url\":\"https:\/\/gijonbasket.com\/\",\"name\":\"gijonbasket\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gijonbasket.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gijonbasket.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gijonbasket.com\/#organization\",\"name\":\"gijonbasket\",\"url\":\"https:\/\/gijonbasket.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg\",\"contentUrl\":\"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg\",\"width\":2000,\"height\":550,\"caption\":\"gijonbasket\"},\"image\":{\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0\",\"name\":\"Cesar Morales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/gijonbasket.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g\",\"caption\":\"Cesar Morales\"},\"url\":\"https:\/\/gijonbasket.com\/en\/author\/cesar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/","og_locale":"en_US","og_type":"article","og_title":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket","og_description":"El Dreamland Gran Canaria anunci\u00f3 el fichaje de Joe Cremo para la pr\u00f3xima temporada. Escolta estadounidense de 29 a\u00f1os y 1.93 m, procedente del Leyma Coru\u00f1a con el que la pasada temporada conquist\u00f3 la Final Four de Ascenso a Liga Endesa, logrando el retorno del conjunto coru\u00f1\u00e9s a la m\u00e1xima categor\u00eda del baloncesto nacional. Joe&hellip;&nbsp;Read More &raquo;Joe Cremo nuevo fichaje del Dreamland Gran Canaria","og_url":"https:\/\/gijonbasket.com\/en\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/","og_site_name":"gijonbasket","article_published_time":"2026-07-28T05:40:44+00:00","article_modified_time":"2026-07-28T05:42:34+00:00","author":"Cesar Morales","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cesar Morales","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#article","isPartOf":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/"},"author":{"name":"Cesar Morales","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0"},"headline":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria","datePublished":"2026-07-28T05:40:44+00:00","dateModified":"2026-07-28T05:42:34+00:00","mainEntityOfPage":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/"},"wordCount":298,"commentCount":0,"publisher":{"@id":"https:\/\/gijonbasket.com\/#organization"},"articleSection":["noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/","url":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/","name":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria - gijonbasket","isPartOf":{"@id":"https:\/\/gijonbasket.com\/#website"},"datePublished":"2026-07-28T05:40:44+00:00","dateModified":"2026-07-28T05:42:34+00:00","breadcrumb":{"@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gijonbasket.com\/2026\/07\/28\/joe-cremo-nuevo-fichaje-del-dreamland-gran-canaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/gijonbasket.com\/"},{"@type":"ListItem","position":2,"name":"Joe Cremo nuevo fichaje del Dreamland Gran Canaria"}]},{"@type":"WebSite","@id":"https:\/\/gijonbasket.com\/#website","url":"https:\/\/gijonbasket.com\/","name":"gijonbasket","description":"","publisher":{"@id":"https:\/\/gijonbasket.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gijonbasket.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gijonbasket.com\/#organization","name":"gijonbasket","url":"https:\/\/gijonbasket.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/","url":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg","contentUrl":"https:\/\/gijonbasket.com\/wp-content\/uploads\/2023\/03\/LogoGijonBasket2.jpg","width":2000,"height":550,"caption":"gijonbasket"},"image":{"@id":"https:\/\/gijonbasket.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/91af9ff03e8eab582ccc344b715907c0","name":"Cesar Morales","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gijonbasket.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab9ddf1e87f7580cae3deefb05a58c5cf4f0c7f96f033fd7dacc23f0e8d149ca?s=96&d=mm&r=g","caption":"Cesar Morales"},"url":"https:\/\/gijonbasket.com\/en\/author\/cesar\/"}]}},"_links":{"self":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/comments?post=12376"}],"version-history":[{"count":2,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12376\/revisions"}],"predecessor-version":[{"id":12379,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/posts\/12376\/revisions\/12379"}],"wp:attachment":[{"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/media?parent=12376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/categories?post=12376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gijonbasket.com\/en\/wp-json\/wp\/v2\/tags?post=12376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}